{"id":3995,"date":"2024-03-14T14:34:23","date_gmt":"2024-03-14T14:34:23","guid":{"rendered":"https:\/\/smile-providers.com\/?page_id=3995"},"modified":"2026-06-27T09:31:38","modified_gmt":"2026-06-27T09:31:38","slug":"zahntourismus","status":"publish","type":"page","link":"https:\/\/smile-provider.com\/de\/turismo-dentale\/","title":{"rendered":"Zahntourismus Albanien"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3995\" class=\"elementor elementor-3995\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f638efc elementor-section-full_width elementor-section-content-middle elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"f638efc\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ec61dde\" data-id=\"ec61dde\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65a6402 elementor-widget elementor-widget-heading\" data-id=\"65a6402\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 15-04-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"anps-heading\" style='text-align: left;'><span class=\" anps-heading__text\" style=\"color: \">Cos'\u00e8 il Turismo Dentale e perch\u00e9 scegliere l\u2019Albania?<\/span><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-243279d elementor-widget elementor-widget-text-editor\" data-id=\"243279d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 15-04-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p data-start=\"371\" data-end=\"703\">Il <strong data-start=\"374\" data-end=\"404\">turismo dentale in Albania<\/strong> \u00e8 una soluzione sempre pi\u00f9 scelta da chi desidera cure odontoiatriche di alta qualit\u00e0 a costi ridotti. Grazie a strutture all\u2019avanguardia e professionisti altamente qualificati, \u00e8 possibile ottenere trattamenti dentali sicuri ed efficaci risparmiando fino al <strong data-start=\"664\" data-end=\"700\">70% rispetto ai prezzi in Italia<\/strong>. Optare per l\u2019<strong data-start=\"718\" data-end=\"745\">odontoiatria in Albania<\/strong> significa non solo ridurre i costi, ma anche ricevere un servizio completo che include volo, trasferimenti e alloggio in <strong data-start=\"867\" data-end=\"885\">hotel 4 stelle<\/strong>, per un\u2019esperienza senza stress e con il massimo comfort.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a8e1ca elementor-widget__width-initial elementor-hidden-tablet elementor-hidden-mobile elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"2a8e1ca\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/smile-provider.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-box.min.css\">\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plane\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M480 192H365.71L260.61 8.06A16.014 16.014 0 0 0 246.71 0h-65.5c-10.63 0-18.3 10.17-15.38 20.39L214.86 192H112l-43.2-57.6c-3.02-4.03-7.77-6.4-12.8-6.4H16.01C5.6 128-2.04 137.78.49 147.88L32 256 .49 364.12C-2.04 374.22 5.6 384 16.01 384H56c5.04 0 9.78-2.37 12.8-6.4L112 320h102.86l-49.03 171.6c-2.92 10.22 4.75 20.4 15.38 20.4h65.5c5.74 0 11.04-3.08 13.89-8.06L365.71 320H480c35.35 0 96-28.65 96-64s-60.65-64-96-64z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tVolo<br> Incluso\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bdadb70 elementor-widget__width-initial elementor-hidden-tablet elementor-hidden-mobile elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"bdadb70\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-taxi\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M462 241.64l-22-84.84c-9.6-35.2-41.6-60.8-76.8-60.8H352V64c0-17.67-14.33-32-32-32H192c-17.67 0-32 14.33-32 32v32h-11.2c-35.2 0-67.2 25.6-76.8 60.8l-22 84.84C21.41 248.04 0 273.47 0 304v48c0 23.63 12.95 44.04 32 55.12V448c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h256v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-40.88c19.05-11.09 32-31.5 32-55.12v-48c0-30.53-21.41-55.96-50-62.36zM96 352c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm20.55-112l17.2-66.36c2.23-8.16 9.59-13.64 15.06-13.64h214.4c5.47 0 12.83 5.48 14.85 12.86L395.45 240h-278.9zM416 352c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTaxi dall'aeroporto\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0fccf8 elementor-widget__width-initial elementor-hidden-tablet elementor-hidden-mobile elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"c0fccf8\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hotel\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M560 64c8.84 0 16-7.16 16-16V16c0-8.84-7.16-16-16-16H16C7.16 0 0 7.16 0 16v32c0 8.84 7.16 16 16 16h15.98v384H16c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h240v-80c0-8.8 7.2-16 16-16h32c8.8 0 16 7.2 16 16v80h240c8.84 0 16-7.16 16-16v-32c0-8.84-7.16-16-16-16h-16V64h16zm-304 44.8c0-6.4 6.4-12.8 12.8-12.8h38.4c6.4 0 12.8 6.4 12.8 12.8v38.4c0 6.4-6.4 12.8-12.8 12.8h-38.4c-6.4 0-12.8-6.4-12.8-12.8v-38.4zm0 96c0-6.4 6.4-12.8 12.8-12.8h38.4c6.4 0 12.8 6.4 12.8 12.8v38.4c0 6.4-6.4 12.8-12.8 12.8h-38.4c-6.4 0-12.8-6.4-12.8-12.8v-38.4zm-128-96c0-6.4 6.4-12.8 12.8-12.8h38.4c6.4 0 12.8 6.4 12.8 12.8v38.4c0 6.4-6.4 12.8-12.8 12.8h-38.4c-6.4 0-12.8-6.4-12.8-12.8v-38.4zM179.2 256h-38.4c-6.4 0-12.8-6.4-12.8-12.8v-38.4c0-6.4 6.4-12.8 12.8-12.8h38.4c6.4 0 12.8 6.4 12.8 12.8v38.4c0 6.4-6.4 12.8-12.8 12.8zM192 384c0-53.02 42.98-96 96-96s96 42.98 96 96H192zm256-140.8c0 6.4-6.4 12.8-12.8 12.8h-38.4c-6.4 0-12.8-6.4-12.8-12.8v-38.4c0-6.4 6.4-12.8 12.8-12.8h38.4c6.4 0 12.8 6.4 12.8 12.8v38.4zm0-96c0 6.4-6.4 12.8-12.8 12.8h-38.4c-6.4 0-12.8-6.4-12.8-12.8v-38.4c0-6.4 6.4-12.8 12.8-12.8h38.4c6.4 0 12.8 6.4 12.8 12.8v38.4z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tHotel<br>4 stelle\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-760db07 elementor-widget__width-initial elementor-hidden-tablet elementor-hidden-mobile elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"760db07\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user-tie\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zm95.8 32.6L272 480l-32-136 32-56h-96l32 56-32 136-47.8-191.4C56.9 292 0 350.3 0 422.4V464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48v-41.6c0-72.1-56.9-130.4-128.2-133.8z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGuida<br> dedicata\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b947f0 elementor-widget elementor-widget-heading\" data-id=\"2b947f0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"anps-heading\" style='text-align: left;'><span class=\" anps-heading__text\" style=\"color: \">Tirana: la capitale del turismo dentale in Albania<\/span><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fed6b03 elementor-widget elementor-widget-text-editor\" data-id=\"fed6b03\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p data-start=\"1464\" data-end=\"1699\">Situata a meno di due ore di volo dall\u2019Italia, Tirana \u00e8 il cuore pulsante del <strong data-start=\"1542\" data-end=\"1578\">turismo odontoiatrico in Albania<\/strong>. La citt\u00e0 offre cliniche moderne con tecnologie all\u2019avanguardia e specialisti formati secondo standard internazionali. Scegliendo <strong data-start=\"1712\" data-end=\"1730\">Smile Provider<\/strong>, avrai un supporto completo dal tuo arrivo fino alla conclusione delle cure. Durante la tua permanenza potrai anche approfittare per scoprire il fascino della citt\u00e0, grazie alla guida locale messa a tua disposizione.<\/p><h2>Clinica certificata e medici che parlano italiano<\/h2><p data-start=\"2012\" data-end=\"2273\">Uno dei principali vantaggi di affidarsi a <strong data-start=\"2055\" data-end=\"2073\">Smile Provider<\/strong> \u00e8 la sicurezza di comunicare senza barriere linguistiche. Il nostro team \u00e8 composto da <strong data-start=\"2161\" data-end=\"2205\">odontoiatri esperti che parlano italiano<\/strong>, garantendo trasparenza e chiarezza in ogni fase del trattamento. I materiali utilizzati sono di alta qualit\u00e0, conformi agli standard europei, e ogni piano di cura \u00e8 personalizzato in base alle esigenze del paziente.<\/p><h3 data-start=\"2320\" data-end=\"2384\"><strong data-start=\"2324\" data-end=\"2382\">Quanto si risparmia con il turismo dentale in Albania?<\/strong><\/h3><p data-start=\"2385\" data-end=\"2718\">Scegliere di effettuare i propri trattamenti odontoiatrici in Albania consente di ottenere un risparmio significativo rispetto ai costi italiani, senza compromettere la qualit\u00e0 delle cure. I pazienti possono accedere a soluzioni all\u2019avanguardia per implantologia, protesi e trattamenti estetici con un notevole vantaggio economico.<\/p><h3 data-start=\"2720\" data-end=\"2772\"><strong data-start=\"2724\" data-end=\"2770\">Prenota ora il tuo trattamento in Albania!<\/strong><\/h3><p data-start=\"2773\" data-end=\"2892\">Non aspettare! Approfitta delle migliori tariffe e ottieni un sorriso perfetto con il <strong data-start=\"2859\" data-end=\"2889\">turismo dentale in Albania<\/strong>.<\/p><p data-start=\"2894\" data-end=\"3114\"><strong data-start=\"2894\" data-end=\"2976\">\ud83d\udc49 Compila ora il modulo per ricevere un preventivo gratuito e personalizzato.<\/strong> Il nostro team ti contatter\u00e0 rapidamente per fornirti tutte le informazioni sui costi e sul piano di cura pi\u00f9 adatto alle tue esigenze.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a0007e elementor-widget elementor-widget-spacer\" data-id=\"4a0007e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 15-04-2024 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-994efe8\" data-id=\"994efe8\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a4938c elementor-widget elementor-widget-text-editor\" data-id=\"5a4938c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #ffffff; font-size: 26px;\"><strong>Prenota ora la tua consulenza gratuita e scopri come trasformare il tuo sorriso risparmiando fino al 70%!<br \/><br \/>Contattaci per un preventivo senza impegno.<\/strong><\/span><\/p><p>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f360-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"360\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/3995#wpcf7-f360-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"360\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f360-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"form-group col-md-12\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"fullname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome e Cognome\" value=\"\" type=\"text\" name=\"fullname\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-group col-md-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telefono\" value=\"\" type=\"tel\" name=\"your-tel\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-group col-md-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-group col-md-12\">\n\t\t<p style=\"font-size: 14px;\"><br \/>\nCarica la panoramica (se disponibile) in jpg, jpeg, png, pdf &#8211; max 5MB\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"file-200\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".jpeg,.png,.jpg,.pdf\" aria-invalid=\"false\" type=\"file\" name=\"file-200\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-group col-md-12\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Messaggio\" name=\"your-message\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-group col-md-12\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner anps-contact-button\" type=\"submit\" value=\"RICHIEDI UNA CONSULENZA PERSONALIZZATA\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e97a5f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e97a5f9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee09fc3\" data-id=\"ee09fc3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-555c7a7 elementor-widget elementor-widget-text-editor\" data-id=\"555c7a7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>I nostri Pacchetti VIP<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-343e2e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"343e2e1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ab8bc36\" data-id=\"ab8bc36\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-621ae81 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"621ae81\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 15-04-2024 *\/\n.elementor-widget-image-box .elementor-image-box-content{width:100%}@media (min-width:768px){.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper,.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{display:flex}.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{text-align:end;flex-direction:row-reverse}.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper{text-align:start;flex-direction:row}.elementor-widget-image-box.elementor-position-top .elementor-image-box-img{margin:auto}.elementor-widget-image-box.elementor-vertical-align-top .elementor-image-box-wrapper{align-items:flex-start}.elementor-widget-image-box.elementor-vertical-align-middle .elementor-image-box-wrapper{align-items:center}.elementor-widget-image-box.elementor-vertical-align-bottom .elementor-image-box-wrapper{align-items:flex-end}}@media (max-width:767px){.elementor-widget-image-box .elementor-image-box-img{margin-left:auto!important;margin-right:auto!important;margin-bottom:15px}}.elementor-widget-image-box .elementor-image-box-img{display:inline-block}.elementor-widget-image-box .elementor-image-box-title a{color:inherit}.elementor-widget-image-box .elementor-image-box-wrapper{text-align:center}.elementor-widget-image-box .elementor-image-box-description{margin:0}<\/style><div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-1.png\" class=\"attachment-full size-full wp-image-3997\" alt=\"dentista in albania\" srcset=\"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-1.png 1080w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-1-300x300.png 300w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-1-1024x1024.png 1024w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-1-150x150.png 150w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-1-768x768.png 768w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-1-500x500.png 500w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-1-600x600.png 600w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-1-100x100.png 100w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">All on 4<\/h3><p class=\"elementor-image-box-description\">Arcata completata con il elementi in zirconio<br> \nTrattamento personalizzato<br>\nImpianti ALL ON 4<br>\nCorone Dentali<br>\nBiglietto Aereo A\/R<br>\nVIP transfer dall'Aeroporto<br>\nGuida Turistica\n\n<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-43a567a\" data-id=\"43a567a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef25ba4 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"ef25ba4\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-2.png\" class=\"attachment-full size-full wp-image-3998\" alt=\"dentista in albania\" srcset=\"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-2.png 1080w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-2-300x300.png 300w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-2-1024x1024.png 1024w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-2-150x150.png 150w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-2-768x768.png 768w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-2-500x500.png 500w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-2-600x600.png 600w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-2-100x100.png 100w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">All on 6<\/h3><p class=\"elementor-image-box-description\">Arcata completate con elementi in zirconio<br>\nTrattamento personalizzato<br>\nImpianti ALL ON 6<br>\nCorone Dentali<br>\nBiglietto Aereo A\/R<br>\nVIP transfer dall'Aeroporto<br>\nGuida Turistica\n<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b7a2a47\" data-id=\"b7a2a47\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22dd52f elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"22dd52f\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-3-2.png\" class=\"attachment-full size-full wp-image-3999\" alt=\"dentista in albania\" srcset=\"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-3-2.png 1080w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-3-2-300x300.png 300w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-3-2-1024x1024.png 1024w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-3-2-150x150.png 150w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-3-2-768x768.png 768w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-3-2-500x500.png 500w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-3-2-600x600.png 600w, https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-3-2-100x100.png 100w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Faccette<\/h3><p class=\"elementor-image-box-description\">Faccette E-Max<br>\nTrattamento funzionale ed estetico<br>\nFaccette  linea Premium<br>\nLunga Durata<br>\nBiglietto Aereo A\/R<br>\nVIP transfer dall'Aeroporto<br>\nGuida Turistica\n<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-320d4b7 e-flex e-con-boxed e-con e-parent\" data-id=\"320d4b7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b66566e elementor-widget elementor-widget-spacer\" data-id=\"b66566e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ce8c39 elementor-section-full_width elementor-section-content-middle elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"4ce8c39\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0dae232\" data-id=\"0dae232\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78c1c27 elementor-widget elementor-widget-heading\" data-id=\"78c1c27\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"anps-heading\" style='text-align: left;'><span class=\" anps-heading__text\" style=\"color: \">Domande frequenti sul turismo dentale in Albania<\/span><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e63f572 elementor-widget elementor-widget-text-editor\" data-id=\"e63f572\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3><strong>Quanto posso risparmiare con il turismo dentale in Albania?<\/strong><\/h3><p>Il risparmio con il turismo dentale in Albania pu\u00f2 essere significativo, arrivando fino al 50-70% rispetto ai prezzi delle cure dentali in Italia. Questo \u00e8 possibile grazie al minor costo della vita e alle agevolazioni fiscali presenti in Albania, che permettono alle cliniche di offrire trattamenti odontoiatrici di alta qualit\u00e0 a prezzi decisamente pi\u00f9 competitivi. Questo vantaggio economico non sacrifica la qualit\u00e0 dei materiali e delle tecnologie impiegate, garantendo cos\u00ec un ottimo rapporto qualit\u00e0-prezzo.<\/p><h3><strong>Quanto \u00e8 sicuro fare trattamenti dentali in Albania?<\/strong><\/h3><p>Fare trattamenti dentali in Albania \u00e8 assolutamente sicuro, soprattutto se ci si affida a cliniche certificate e professionali come la nostra. Le cliniche specializzate nel turismo dentale rispettano gli standard internazionali di sicurezza e igiene e utilizzano attrezzature moderne e materiali di alta qualit\u00e0, spesso di provenienza europea. Inoltre, i professionisti sono altamente qualificati, molti dei quali con formazione e aggiornamenti continui. La sicurezza e la salute dei pazienti sono priorit\u00e0 assolute.<\/p><h3><strong>Come organizzare il viaggio per il turismo dentale in Albania?<\/strong><\/h3><p>Organizzare il viaggio per il turismo dentale in Albania \u00e8 semplice e conveniente. Il nostro team ti supporta passo dopo passo, dalla prenotazione della visita preliminare al supporto logistico per il viaggio. Puoi raggiungere l\u2019Albania facilmente con voli diretti dai principali aeroporti italiani, mentre all\u2019arrivo possiamo assisterti con trasferimenti locali e, se necessario, alloggio vicino alla clinica. Contattaci per avere maggiori informazioni e pianificare al meglio il tuo viaggio.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56b9b70 elementor-widget elementor-widget-spacer\" data-id=\"56b9b70\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61a7ed7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61a7ed7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cbef03c\" data-id=\"cbef03c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24de958 elementor-widget elementor-widget-text-editor\" data-id=\"24de958\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>I nostri servizi per la salute del tuo sorriso<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e486979 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e486979\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-bd3c2c0\" data-id=\"bd3c2c0\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-84c712f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"84c712f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-aab02c0\" data-id=\"aab02c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b07cb3d elementor-widget elementor-widget-anps-icon\" data-id=\"b07cb3d\" data-element_type=\"widget\" data-widget_type=\"anps-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class='anps-icon anps-icon--center anps-icon--v-top'><div class='anps-icon__col anps-icon__col--icon'><div style='color: #68E2E7;' class='anps-icon__wrap'><div  class=\"anps-icon__image__svg\"  style=\"color: #68E2E7;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 40 40\" >\n<g>\n\t<line fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" x1=\"16\" y1=\"28.9997044\" x2=\"24\" y2=\"28.9997044\"\/>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M23.9683628,26C25.5778694,26,30,21.5319424,30,11.7910805C30,8.9337606,26.4971752,6,20,6\n\t\ts-9.999999,2.9337606-9.999999,5.7910805C10.000001,21.5319424,14.4221315,26,16.0316391,26H23.9683628z\"\/>\n\t<line fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" x1=\"16\" y1=\"31.9997044\" x2=\"24\" y2=\"31.9997044\"\/>\n\t<line fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" x1=\"18\" y1=\"34.9997063\" x2=\"22\" y2=\"34.9997063\"\/>\n<\/g>\n<\/svg>\n<\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff7daf0 elementor-widget elementor-widget-heading\" data-id=\"ff7daf0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"anps-heading\" style='text-align: center;'><a class=\" anps-heading__link\" href=https:\/\/smile-provider.com\/impianti-dentali\/ style=\"color: \">Implantologia<\/a><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-684a258\" data-id=\"684a258\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f77d2c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f77d2c7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-471e5c9\" data-id=\"471e5c9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99c1972 elementor-widget elementor-widget-anps-icon\" data-id=\"99c1972\" data-element_type=\"widget\" data-widget_type=\"anps-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class='anps-icon anps-icon--center anps-icon--v-top'><div class='anps-icon__col anps-icon__col--icon'><div style='color: #68E2E7;' class='anps-icon__wrap'><div  class=\"anps-icon__image__svg\"  style=\"color: #68E2E7;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 40 40\" >\n<g>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M16.0316372,10C14.5003405,10.541667,10,14.6949673,10,24.9305191C10,27.9329491,13.5028248,30,20,30\n\t\ts10-2.0670509,10-5.0694809C30,14.6949673,25.4996605,10.541667,23.9683628,10\"\/>\n\t<circle fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" cx=\"20\" cy=\"20\" r=\"4\"\/>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M36.0316391,10C34.5003395,10.541667,30,14.6949673,30,24.9305191\n\t\tc0,2.3122959,2.0775871,4.0698013,6.0005035,4.7555866\"\/>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M4,10c1.5312977,0.541667,6.0316381,4.6949673,6.0316381,14.9305191\n\t\tc0,2.3122959-2.077589,4.0698013-6.0005031,4.7555866\"\/>\n\t<line fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" x1=\"24\" y1=\"20\" x2=\"36.0316391\" y2=\"20\"\/>\n\t<line fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" x1=\"4.0158191\" y1=\"20\" x2=\"16\" y2=\"20\"\/>\n<\/g>\n<\/svg>\n<\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c04fc7 elementor-widget elementor-widget-heading\" data-id=\"9c04fc7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"anps-heading\" style='text-align: center;'><a class=\" anps-heading__link\" href=https:\/\/smile-provider.com\/protesi-dentali\/ style=\"color: \">Protesi dentali<\/a><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-749e933\" data-id=\"749e933\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-954d78b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"954d78b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3746d06\" data-id=\"3746d06\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3633145 elementor-widget elementor-widget-anps-icon\" data-id=\"3633145\" data-element_type=\"widget\" data-widget_type=\"anps-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class='anps-icon anps-icon--center anps-icon--v-top'><div class='anps-icon__col anps-icon__col--icon'><div style='color: #68E2E7;' class='anps-icon__wrap'><div  class=\"anps-icon__image__svg\"  style=\"color: #68E2E7;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 40 40\" >\n<g>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M32.9728966,16.6541595C32.5278053,29.2184277,26.7220173,35,24.5557079,35\n\t\tC21.9565315,35,21.8327618,29.9762535,19,29.9762535S16.0434685,35,13.444293,35\n\t\tc-2.2533092,0-8.4442921-6.2552795-8.4442921-19.8924866C5.0000005,11.1072645,9.9039555,7,19,7\n\t\tc2.1147308,0,4.0028763,0.2220025,5.6554871,0.6130495\"\/>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M10.0178108,17.0062828c0-2.7614231,2.2385759-4.999999,5-4.999999\"\/>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M28.4988499,5c0,4.1421356-3.3578644,7.5-7.5,7.5c4.1421356,0,7.5,3.3578644,7.5,7.5\n\t\tc0-4.1421356,3.3578644-7.5,7.5000019-7.5C31.8567142,12.5,28.4988499,9.1421356,28.4988499,5z\"\/>\n<\/g>\n<\/svg>\n<\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3078438 elementor-widget elementor-widget-heading\" data-id=\"3078438\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"anps-heading\" style='text-align: center;'><a class=\" anps-heading__link\" href=https:\/\/smile-provider.com\/faccette-dentali-estetiche\/ style=\"color: \">Estetica dentale<\/a><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bed5944 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"bed5944\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f7e9705\" data-id=\"f7e9705\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-53dec81 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"53dec81\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-446e73a\" data-id=\"446e73a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddd1551 elementor-widget elementor-widget-anps-icon\" data-id=\"ddd1551\" data-element_type=\"widget\" data-widget_type=\"anps-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class='anps-icon anps-icon--center anps-icon--v-top'><div class='anps-icon__col anps-icon__col--icon'><div style='color: #68E2E7;' class='anps-icon__wrap'><div  class=\"anps-icon__image__svg\"  style=\"color: #68E2E7;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 40 40\">\n<g>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M20,25.4116096C17.9765987,25.4116096,17.8881912,29,16.0316372,29C14.4221315,29,10,24.5319424,10,14.7910805\n\t\tC10,11.9337606,13.5028248,9,20,9s10,2.9337606,10,5.7910805C30,24.5319424,25.5778694,29,23.9683628,29\n\t\tC22.1118088,29,22.0234013,25.4116096,20,25.4116096z\"\/>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M20.0236034,1C19.853157,1,3.8047094,4.9552875,3.8047094,4.9552875S3,5.3469148,3,5.7764063v13.870429\n\t\tc0,15.246254,15.9567375,19.0034103,16.6356449,19.2819405c0.2323647,0.0952415,0.4980106,0.0944138,0.7269745,0.0008278\n\t\tC21.0432625,38.6502457,37,34.8930893,37,19.6468353V5.7764063c0-0.4294915-0.8144073-0.8218627-0.8144073-0.8218627\n\t\tS20.1468086,1,20.0236034,1z\"\/>\n<\/g>\n<\/svg>\n<\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fff27ca elementor-widget elementor-widget-heading\" data-id=\"fff27ca\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"anps-heading\" style='text-align: center;'><span class=\" anps-heading__text\" style=\"color: \">Ortodonzia<\/span><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9051dd8\" data-id=\"9051dd8\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5655d4c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5655d4c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-842fb58\" data-id=\"842fb58\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0d72b2 elementor-widget elementor-widget-anps-icon\" data-id=\"d0d72b2\" data-element_type=\"widget\" data-widget_type=\"anps-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class='anps-icon anps-icon--center anps-icon--v-top'><div class='anps-icon__col anps-icon__col--icon'><div style='color: #68E2E7;' class='anps-icon__wrap'><div  class=\"anps-icon__image__svg\"  style=\"color: #68E2E7;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 40 40\" >\n<g>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M20,28.9762535C17.1672401,28.9762535,17.0434685,34,14.444293,34\n\t\tc-2.2533092,0-8.4442921-6.2552795-8.4442921-19.8924866C6.0000005,10.1072645,10.9039555,6,20,6s14,4.1072645,14,8.1075125\n\t\tC34,27.7447205,27.8090172,34,25.5557079,34C22.9565315,34,22.8327618,28.9762535,20,28.9762535z\"\/>\n\t<circle fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" cx=\"14\" cy=\"15\" r=\"4\"\/>\n\t<polyline fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" points=\"20.979166,23 24.9969292,19.0072041 30.0187664,19.0072041 33.8333321,15.020833 \t\"\/>\n<\/g>\n<\/svg>\n<\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-066cab5 elementor-widget elementor-widget-heading\" data-id=\"066cab5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"anps-heading\" style='text-align: center;'><span class=\" anps-heading__text\" style=\"color: \">Parodontologia<\/span><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9c00fd3\" data-id=\"9c00fd3\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-669c1e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"669c1e8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ea66bf2\" data-id=\"ea66bf2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43b2b2d elementor-widget elementor-widget-anps-icon\" data-id=\"43b2b2d\" data-element_type=\"widget\" data-widget_type=\"anps-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class='anps-icon anps-icon--center anps-icon--v-top'><div class='anps-icon__col anps-icon__col--icon'><div style='color: #68E2E7;' class='anps-icon__wrap'><div  class=\"anps-icon__image__svg\"  style=\"color: #68E2E7;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 40 40\">\n<g>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M35,33.9921684c0,2.75-2.25,5-5,5H10c-2.75,0-5-2.25-5-5v-23c0-2.75,2.25-5,5-5h20c2.75,0,5,2.25,5,5\n\t\tV33.9921684z\"\/>\n\t<line fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" x1=\"11.0087671\" y1=\"34.0058975\" x2=\"18.0087681\" y2=\"34.0058975\"\/>\n\t<line fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" x1=\"22.0087681\" y1=\"34.0058975\" x2=\"29.0087681\" y2=\"34.0058975\"\/>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M20,26.4881268C18.5836201,26.4881268,18.5217342,29,17.222147,29\n\t\tc-1.1266556,0-4.222146-3.1276398-4.222146-9.9462433C13.000001,17.0536327,15.4519777,15,20,15s7,2.0536327,7,4.0537567\n\t\tC27,25.8723602,23.9045086,29,22.7778549,29C21.4782658,29,21.4163818,26.4881268,20,26.4881268z\"\/>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M27,6.3730426v2.3333335c0,1.2886648-1.0446682,2.333333-2.333334,2.333333h-9.333333\n\t\tC14.0446692,11.0397091,13,9.9950409,13,8.7063761V6.3730426\"\/>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M15.5,5.5166254c0-2.4852812,2.014719-4.5,4.5-4.5s4.5,2.0147188,4.5,4.5\"\/>\n<\/g>\n<\/svg>\n<\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8a7b22 elementor-widget elementor-widget-heading\" data-id=\"c8a7b22\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"anps-heading\" style='text-align: center;'><span class=\" anps-heading__text\" style=\"color: \">Endodonzia<\/span><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f8f22b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9f8f22b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-53434f2\" data-id=\"53434f2\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c899ff9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c899ff9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-982d830\" data-id=\"982d830\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15c2448 elementor-widget elementor-widget-anps-icon\" data-id=\"15c2448\" data-element_type=\"widget\" data-widget_type=\"anps-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class='anps-icon anps-icon--center anps-icon--v-top'><div class='anps-icon__col anps-icon__col--icon'><div style='color: #68E2E7;' class='anps-icon__wrap'><div  class=\"anps-icon__image__svg\"  style=\"color: #68E2E7;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 40 40\" >\n<g>\n\t<line fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" x1=\"16\" y1=\"28.9997044\" x2=\"24\" y2=\"28.9997044\"\/>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M23.9683628,26C25.5778694,26,30,21.5319424,30,11.7910805C30,8.9337606,26.4971752,6,20,6\n\t\ts-9.999999,2.9337606-9.999999,5.7910805C10.000001,21.5319424,14.4221315,26,16.0316391,26H23.9683628z\"\/>\n\t<line fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" x1=\"16\" y1=\"31.9997044\" x2=\"24\" y2=\"31.9997044\"\/>\n\t<line fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" x1=\"18\" y1=\"34.9997063\" x2=\"22\" y2=\"34.9997063\"\/>\n<\/g>\n<\/svg>\n<\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f11fbcf elementor-widget elementor-widget-heading\" data-id=\"f11fbcf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"anps-heading\" style='text-align: center;'><span class=\" anps-heading__text\" style=\"color: \">Chirurgia Maxillo-Facciale<\/span><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a92c46c\" data-id=\"a92c46c\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-de814ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de814ef\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0a8d584\" data-id=\"0a8d584\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-710cc14 elementor-widget elementor-widget-anps-icon\" data-id=\"710cc14\" data-element_type=\"widget\" data-widget_type=\"anps-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class='anps-icon anps-icon--center anps-icon--v-top'><div class='anps-icon__col anps-icon__col--icon'><div style='color: #68E2E7;' class='anps-icon__wrap'><div  class=\"anps-icon__image__svg\"  style=\"color: #68E2E7;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 40 40\" >\n<g>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M32.9728966,16.6541595C32.5278053,29.2184277,26.7220173,35,24.5557079,35\n\t\tC21.9565315,35,21.8327618,29.9762535,19,29.9762535S16.0434685,35,13.444293,35\n\t\tc-2.2533092,0-8.4442921-6.2552795-8.4442921-19.8924866C5.0000005,11.1072645,9.9039555,7,19,7\n\t\tc2.1147308,0,4.0028763,0.2220025,5.6554871,0.6130495\"\/>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M10.0178108,17.0062828c0-2.7614231,2.2385759-4.999999,5-4.999999\"\/>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M28.4988499,5c0,4.1421356-3.3578644,7.5-7.5,7.5c4.1421356,0,7.5,3.3578644,7.5,7.5\n\t\tc0-4.1421356,3.3578644-7.5,7.5000019-7.5C31.8567142,12.5,28.4988499,9.1421356,28.4988499,5z\"\/>\n<\/g>\n<\/svg>\n<\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e803d92 elementor-widget elementor-widget-heading\" data-id=\"e803d92\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"anps-heading\" style='text-align: center;'><span class=\" anps-heading__text\" style=\"color: \">Sedazione<\/span><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7f37bb0\" data-id=\"7f37bb0\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1fdd0fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1fdd0fa\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4c97bc0\" data-id=\"4c97bc0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d379370 elementor-widget elementor-widget-anps-icon\" data-id=\"d379370\" data-element_type=\"widget\" data-widget_type=\"anps-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class='anps-icon anps-icon--center anps-icon--v-top'><div class='anps-icon__col anps-icon__col--icon'><div style='color: #68E2E7;' class='anps-icon__wrap'><div  class=\"anps-icon__image__svg\"  style=\"color: #68E2E7;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 40 40\">\n<g>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M20,25.4116096C17.9765987,25.4116096,17.8881912,29,16.0316372,29C14.4221315,29,10,24.5319424,10,14.7910805\n\t\tC10,11.9337606,13.5028248,9,20,9s10,2.9337606,10,5.7910805C30,24.5319424,25.5778694,29,23.9683628,29\n\t\tC22.1118088,29,22.0234013,25.4116096,20,25.4116096z\"\/>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M20.0236034,1C19.853157,1,3.8047094,4.9552875,3.8047094,4.9552875S3,5.3469148,3,5.7764063v13.870429\n\t\tc0,15.246254,15.9567375,19.0034103,16.6356449,19.2819405c0.2323647,0.0952415,0.4980106,0.0944138,0.7269745,0.0008278\n\t\tC21.0432625,38.6502457,37,34.8930893,37,19.6468353V5.7764063c0-0.4294915-0.8144073-0.8218627-0.8144073-0.8218627\n\t\tS20.1468086,1,20.0236034,1z\"\/>\n<\/g>\n<\/svg>\n<\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f21a50 elementor-widget elementor-widget-heading\" data-id=\"1f21a50\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"anps-heading\" style='text-align: center;'><span class=\" anps-heading__text\" style=\"color: \">Faccette dentali<\/span><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5435b60 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5435b60\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9dfe207\" data-id=\"9dfe207\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0e1f026 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e1f026\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7a33816\" data-id=\"7a33816\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df689e2 elementor-widget elementor-widget-anps-icon\" data-id=\"df689e2\" data-element_type=\"widget\" data-widget_type=\"anps-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class='anps-icon anps-icon--center anps-icon--v-top'><div class='anps-icon__col anps-icon__col--icon'><div style='color: #68E2E7;' class='anps-icon__wrap'><div  class=\"anps-icon__image__svg\"  style=\"color: #68E2E7;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 40 40\">\n<g>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M35,33.9921684c0,2.75-2.25,5-5,5H10c-2.75,0-5-2.25-5-5v-23c0-2.75,2.25-5,5-5h20c2.75,0,5,2.25,5,5\n\t\tV33.9921684z\"\/>\n\t<line fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" x1=\"11.0087671\" y1=\"34.0058975\" x2=\"18.0087681\" y2=\"34.0058975\"\/>\n\t<line fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" x1=\"22.0087681\" y1=\"34.0058975\" x2=\"29.0087681\" y2=\"34.0058975\"\/>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M20,26.4881268C18.5836201,26.4881268,18.5217342,29,17.222147,29\n\t\tc-1.1266556,0-4.222146-3.1276398-4.222146-9.9462433C13.000001,17.0536327,15.4519777,15,20,15s7,2.0536327,7,4.0537567\n\t\tC27,25.8723602,23.9045086,29,22.7778549,29C21.4782658,29,21.4163818,26.4881268,20,26.4881268z\"\/>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M27,6.3730426v2.3333335c0,1.2886648-1.0446682,2.333333-2.333334,2.333333h-9.333333\n\t\tC14.0446692,11.0397091,13,9.9950409,13,8.7063761V6.3730426\"\/>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M15.5,5.5166254c0-2.4852812,2.014719-4.5,4.5-4.5s4.5,2.0147188,4.5,4.5\"\/>\n<\/g>\n<\/svg>\n<\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c7fe91 elementor-widget elementor-widget-heading\" data-id=\"5c7fe91\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"anps-heading\" style='text-align: center;'><span class=\" anps-heading__text\" style=\"color: \">Radiologia & Diagnostica per immagini<\/span><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-0030514 elementor-widget elementor-widget-heading\" data-id=\"0030514\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"anps-heading\" style='text-align: center;'><span class=\" anps-heading__text\" style=\"color: \"><\/span><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-815c593\" data-id=\"815c593\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c4319ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c4319ae\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d772ad7\" data-id=\"d772ad7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9c70f7 elementor-widget elementor-widget-anps-icon\" data-id=\"a9c70f7\" data-element_type=\"widget\" data-widget_type=\"anps-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class='anps-icon anps-icon--center anps-icon--v-top'><div class='anps-icon__col anps-icon__col--icon'><div style='color: #68E2E7;' class='anps-icon__wrap'><div  class=\"anps-icon__image__svg\"  style=\"color: #68E2E7;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 40 40\" >\n<g>\n\t<path fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" d=\"M20,28.9762535C17.1672401,28.9762535,17.0434685,34,14.444293,34\n\t\tc-2.2533092,0-8.4442921-6.2552795-8.4442921-19.8924866C6.0000005,10.1072645,10.9039555,6,20,6s14,4.1072645,14,8.1075125\n\t\tC34,27.7447205,27.8090172,34,25.5557079,34C22.9565315,34,22.8327618,28.9762535,20,28.9762535z\"\/>\n\t<circle fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" cx=\"14\" cy=\"15\" r=\"4\"\/>\n\t<polyline fill=\"none\" stroke=\"currentColor\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"4%\" points=\"20.979166,23 24.9969292,19.0072041 30.0187664,19.0072041 33.8333321,15.020833 \t\"\/>\n<\/g>\n<\/svg>\n<\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-564ed65 elementor-widget elementor-widget-heading\" data-id=\"564ed65\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"anps-heading\" style='text-align: center;'><span class=\" anps-heading__text\" style=\"color: \">Odontoiatria Pediatrica<\/span><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-37943e7\" data-id=\"37943e7\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d37fc0a elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"d37fc0a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-41aa129\" data-id=\"41aa129\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a313736\" data-id=\"a313736\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1caf365 elementor-widget elementor-widget-heading\" data-id=\"1caf365\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"anps-heading\" style='text-align: left;'><span class=\" anps-heading__text\" style=\"color: \">Chi Siamo<\/span><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c724e97 elementor-widget elementor-widget-text-editor\" data-id=\"c724e97\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Smile Provider \u00e8 un <strong>centro odontoiatrico con sede a Tirana, in Albania<\/strong>, specializzato in un&#8217;ampia gamma di trattamenti odontoiatrici per la salute orale, dagli impianti dentali alla rigenerazione ossea, dalla cura della parodontite alle protesi dentarie. Offrie, inoltre, servizi di odontoiatria estetica, ortodonzia, correzione dei difetti dentali e trattamenti specifici per le patologie del complesso cranio-cervico-mandibolare.<\/p><p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); background-color: var(--anps-page-bg);\">Siamo un <strong>centro di eccellenza<\/strong>, riconosciuto per la nostra esperienza consolidata, l&#8217;uso di strumenti tecnologici all\u2019avanguardia e l\u2019impiego di materiali di altissima qualit\u00e0, garantendo r<strong>isultati di eccellenza e cure personalizzate per ogni paziente<\/strong>.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da35586 elementor-widget elementor-widget-spacer\" data-id=\"da35586\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f8241e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f8241e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7469bf5\" data-id=\"7469bf5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a21847 elementor-widget elementor-widget-text-editor\" data-id=\"4a21847\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><div class=\"tmm tmm_staff-medico\"><div class=\"tmm_4_columns tmm_wrap tmm_theme_f\"><span class=\"tmm_two_containers_tablet\"><\/span><div class=\"tmm_container\"><div class=\"tmm_member\" style=\"border-top:#39d9e0 solid 5px;\"><div class=\"tmm_photo tmm_pic_staff-medico_0\" style=\"background: url(https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/FOTO-23-scaled-2.jpg); margin-left: auto; margin-right:auto; background-size:cover !important;\"><\/div><div class=\"tmm_textblock\"><div class=\"tmm_names\"><span class=\"tmm_fname\">Dott.ssa Denisa<\/span> <span class=\"tmm_lname\">Hazballa<\/span><\/div><div class=\"tmm_job\">Chirurgo Orale e Implantologa<\/div><div class=\"tmm_scblock\"><\/div><\/div><\/div><div class=\"tmm_member\" style=\"border-top:#39d9e0 solid 5px;\"><div class=\"tmm_photo tmm_pic_staff-medico_1\" style=\"background: url(https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/FOTO-16-scaled-e1706885523151.jpg); margin-left: auto; margin-right:auto; background-size:cover !important;\"><\/div><div class=\"tmm_textblock\"><div class=\"tmm_names\"><span class=\"tmm_fname\">Dott. Kostika<\/span> <span class=\"tmm_lname\">Vera<\/span><\/div><div class=\"tmm_job\">Chirurgo Orale e Implantologa<\/div><div class=\"tmm_scblock\"><\/div><\/div><\/div><span class=\"tmm_two_containers_tablet\"><\/span><div class=\"tmm_member\" style=\"border-top:#39d9e0 solid 5px;\"><div class=\"tmm_photo tmm_pic_staff-medico_2\" style=\"background: url(https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/FOTO-25-scaled-1.jpg); margin-left: auto; margin-right:auto; background-size:cover !important;\"><\/div><div class=\"tmm_textblock\"><div class=\"tmm_names\"><span class=\"tmm_fname\">Dott.ssa Xhorxhina<\/span> <span class=\"tmm_lname\">Hysellari<\/span><\/div><div class=\"tmm_job\">Medico Odontostomatologo<\/div><div class=\"tmm_scblock\"><\/div><\/div><\/div><div class=\"tmm_member\" style=\"border-top:#39d9e0 solid 5px;\"><div class=\"tmm_photo tmm_pic_staff-medico_3\" style=\"background: url(https:\/\/smile-provider.com\/wp-content\/uploads\/2025\/06\/205A2329-scaled.jpg); margin-left: auto; margin-right:auto; background-size:cover !important;\"><\/div><div class=\"tmm_textblock\"><div class=\"tmm_names\"><span class=\"tmm_fname\">Dott.ssa Donatela<\/span> <span class=\"tmm_lname\">Lasku<\/span><\/div><div class=\"tmm_job\">Medico Stomatologo General<\/div><div class=\"tmm_scblock\"><\/div><\/div><\/div><span class=\"tmm_two_containers_tablet\"><\/span><\/div><span class=\"tmm_columns_containers_desktop\"><\/span><div class=\"tmm_container\"><div class=\"tmm_member\" style=\"border-top:#39d9e0 solid 5px;\"><div class=\"tmm_photo tmm_pic_staff-medico_4\" style=\"background: url(https:\/\/smile-provider.com\/wp-content\/uploads\/2025\/06\/205A2317-scaled.jpg); margin-left: auto; margin-right:auto; background-size:cover !important;\"><\/div><div class=\"tmm_textblock\"><div class=\"tmm_names\"><span class=\"tmm_fname\">Dott. Xhoel<\/span> <span class=\"tmm_lname\">Nonaj<\/span><\/div><div class=\"tmm_job\">Medico Odontostomatologo<\/div><div class=\"tmm_scblock\"><\/div><\/div><\/div><div class=\"tmm_member\" style=\"border-top:#39d9e0 solid 5px;\"><div class=\"tmm_photo tmm_pic_staff-medico_5\" style=\"background: url(https:\/\/smile-provider.com\/wp-content\/uploads\/2025\/06\/205A2311-scaled.jpg); margin-left: auto; margin-right:auto; background-size:cover !important;\"><\/div><div class=\"tmm_textblock\"><div class=\"tmm_names\"><span class=\"tmm_fname\">Dott.ssa Rozalinda<\/span> <span class=\"tmm_lname\">Dalipaj<\/span><\/div><div class=\"tmm_job\">Medico Odontostomatologo<\/div><div class=\"tmm_scblock\"><\/div><\/div><\/div><span class=\"tmm_two_containers_tablet\"><\/span><div class=\"tmm_member\" style=\"border-top:#39d9e0 solid 5px;\"><div class=\"tmm_photo tmm_pic_staff-medico_6\" style=\"background: url(https:\/\/smile-provider.com\/wp-content\/uploads\/2026\/01\/dott-eglis-hoxha.png); margin-left: auto; margin-right:auto; background-size:cover !important;\"><\/div><div class=\"tmm_textblock\"><div class=\"tmm_names\"><span class=\"tmm_fname\">Dott. Eglis<\/span> <span class=\"tmm_lname\">Hoxha<\/span><\/div><div class=\"tmm_job\">Medico Stomatologo<\/div><div class=\"tmm_scblock\"><\/div><\/div><\/div><div class=\"tmm_member\" style=\"border-top:#39d9e0 solid 5px;\"><div class=\"tmm_photo tmm_pic_staff-medico_7\" style=\"background: url(https:\/\/smile-provider.com\/wp-content\/uploads\/2026\/01\/dott-ssa-rexhina-saliaj.png); margin-left: auto; margin-right:auto; background-size:cover !important;\"><\/div><div class=\"tmm_textblock\"><div class=\"tmm_names\"><span class=\"tmm_fname\">Dott.ssa Rexhina<\/span> <span class=\"tmm_lname\">Saliaj<\/span><\/div><div class=\"tmm_job\">Medico Odontostomatologo<\/div><div class=\"tmm_scblock\"><\/div><\/div><\/div><span class=\"tmm_two_containers_tablet\"><\/span><\/div><span class=\"tmm_columns_containers_desktop\"><\/span><div class=\"tmm_container\"><div class=\"tmm_member\" style=\"border-top:#39d9e0 solid 5px;\"><div class=\"tmm_photo tmm_pic_staff-medico_8\" style=\"background: url(https:\/\/smile-provider.com\/wp-content\/uploads\/2026\/01\/dott-jetmir-dani.png); margin-left: auto; margin-right:auto; background-size:cover !important;\"><\/div><div class=\"tmm_textblock\"><div class=\"tmm_names\"><span class=\"tmm_fname\">Dott. Jetmir<\/span> <span class=\"tmm_lname\">Dani<\/span><\/div><div class=\"tmm_job\">Medico Protesista<\/div><div class=\"tmm_scblock\"><\/div><\/div><\/div><div style=\"clear:both;\"><\/div><\/div><\/div><\/div><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-465d36b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"465d36b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e154ea4\" data-id=\"e154ea4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79a1427 elementor-widget elementor-widget-text-editor\" data-id=\"79a1427\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>Perch\u00e8 affidarti a noi:<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b6e2124 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b6e2124\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-68d858c\" data-id=\"68d858c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddd9690 elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"ddd9690\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-medal\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M223.75 130.75L154.62 15.54A31.997 31.997 0 0 0 127.18 0H16.03C3.08 0-4.5 14.57 2.92 25.18l111.27 158.96c29.72-27.77 67.52-46.83 109.56-53.39zM495.97 0H384.82c-11.24 0-21.66 5.9-27.44 15.54l-69.13 115.21c42.04 6.56 79.84 25.62 109.56 53.38L509.08 25.18C516.5 14.57 508.92 0 495.97 0zM256 160c-97.2 0-176 78.8-176 176s78.8 176 176 176 176-78.8 176-176-78.8-176-176-176zm92.52 157.26l-37.93 36.96 8.97 52.22c1.6 9.36-8.26 16.51-16.65 12.09L256 393.88l-46.9 24.65c-8.4 4.45-18.25-2.74-16.65-12.09l8.97-52.22-37.93-36.96c-6.82-6.64-3.05-18.23 6.35-19.59l52.43-7.64 23.43-47.52c2.11-4.28 6.19-6.39 10.28-6.39 4.11 0 8.22 2.14 10.33 6.39l23.43 47.52 52.43 7.64c9.4 1.36 13.17 12.95 6.35 19.59z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tQualit\u00e0 garantita\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAffidati al nostro personale specializzato: ci affidiamo ai migliori fornitori per materiali di altissima qualit\u00e0. \nLa tua salute \u00e8 la nostra priorit\u00e0.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1ab1ff7\" data-id=\"1ab1ff7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c318ee6 elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"c318ee6\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-smile\" viewBox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M248 8C111 8 0 119 0 256s111 248 248 248 248-111 248-248S385 8 248 8zm0 448c-110.3 0-200-89.7-200-200S137.7 56 248 56s200 89.7 200 200-89.7 200-200 200zm-80-216c17.7 0 32-14.3 32-32s-14.3-32-32-32-32 14.3-32 32 14.3 32 32 32zm160 0c17.7 0 32-14.3 32-32s-14.3-32-32-32-32 14.3-32 32 14.3 32 32 32zm4 72.6c-20.8 25-51.5 39.4-84 39.4s-63.2-14.3-84-39.4c-8.5-10.2-23.7-11.5-33.8-3.1-10.2 8.5-11.5 23.6-3.1 33.8 30 36 74.1 56.6 120.9 56.6s90.9-20.6 120.9-56.6c8.5-10.2 7.1-25.3-3.1-33.8-10.1-8.4-25.3-7.1-33.8 3.1z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tZero Pensieri\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNon preoccuparti di nulla!\nPenseremo noi a piano di cure, voli, alloggio e trasferimenti. Avrai anche una guida a tua disposizione per il tuo tempo libero!\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-752da24\" data-id=\"752da24\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78590c7 elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"78590c7\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-euro-sign\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M310.706 413.765c-1.314-6.63-7.835-10.872-14.424-9.369-10.692 2.439-27.422 5.413-45.426 5.413-56.763 0-101.929-34.79-121.461-85.449h113.689a12 12 0 0 0 11.708-9.369l6.373-28.36c1.686-7.502-4.019-14.631-11.708-14.631H115.22c-1.21-14.328-1.414-28.287.137-42.245H261.95a12 12 0 0 0 11.723-9.434l6.512-29.755c1.638-7.484-4.061-14.566-11.723-14.566H130.184c20.633-44.991 62.69-75.03 117.619-75.03 14.486 0 28.564 2.25 37.851 4.145 6.216 1.268 12.347-2.498 14.002-8.623l11.991-44.368c1.822-6.741-2.465-13.616-9.326-14.917C290.217 34.912 270.71 32 249.635 32 152.451 32 74.03 92.252 45.075 176H12c-6.627 0-12 5.373-12 12v29.755c0 6.627 5.373 12 12 12h21.569c-1.009 13.607-1.181 29.287-.181 42.245H12c-6.627 0-12 5.373-12 12v28.36c0 6.627 5.373 12 12 12h30.114C67.139 414.692 145.264 480 249.635 480c26.301 0 48.562-4.544 61.101-7.788 6.167-1.595 10.027-7.708 8.788-13.957l-8.818-44.49z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRisparmio garantito\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLe tariffe migliori senza compromessi.\nScegli la soluzione pi\u00f9 sicura per la tua salute e per ritrovare subito il tuo sorriso.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68cced9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68cced9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-80c799c\" data-id=\"80c799c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45e9843 elementor-widget elementor-widget-text-editor\" data-id=\"45e9843\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>La parola ai nostri Pazienti<\/h2><p>Ascolta il parere di chi prima di te ha deciso di affidarsi alle nostre cure!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c8fc39 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c8fc39\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-555168c\" data-id=\"555168c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f725fc4 elementor-widget elementor-widget-text-editor\" data-id=\"f725fc4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><pre class=\"ti-widget\" style=\"display: none\"><template id=\"trustindex-google-widget-html\"><div class=\" ti-widget  ti-goog ti-disable-font ti-show-rating-text ti-review-text-mode-readmore ti-text-align-left\" data-no-translation=\"true\" data-time-locale=\"%d %s fa|oggi|giorno|giorni|settimana|settimane|mese|mesi|anno|anni\" data-plugin-version=\"13.2.9\" data-layout-id=\"5\" data-layout-category=\"slider\" data-set-id=\"light-background\" data-pid=\"\" data-language=\"it\" data-close-locale=\"Vicino\" data-review-target-width=\"275\" data-css-version=\"2\" data-reply-by-locale=\"Risposta dal proprietario\" data-only-rating-locale=\"Questo utente ha lasciato solo una valutazione.\" data-pager-autoplay-timeout=\"6\"> <div class=\"ti-widget-container ti-col-4\"> <div class=\"ti-footer ti-footer-grid source-Google\"> <div class=\"ti-fade-container\"> <div class=\"ti-rating-text\"> <strong class=\"ti-rating ti-rating-large\"> ECCELLENTE <\/strong> <\/div> <span class=\"ti-stars star-lg\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-rating-text\"> <span class=\"nowrap\">In base a <strong>475 recensioni<\/strong><\/span> <\/div> <div class=\"ti-large-logo\"> <div class=\"ti-v-center\"> <trustindex-image class=\"ti-logo-fb\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/logo.svg\" width=\"150\" height=\"25\" loading=\"lazy\" alt=\"Google\"><\/trustindex-image> <\/div> <\/div> <\/div> <\/div> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\" aria-label=\"Prossima recensione\" role=\"button\" tabindex=\"0\"><\/div> <div class=\"ti-prev\" aria-label=\"Recensione precedente\" role=\"button\" tabindex=\"0\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" data-time=\"1783296000\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Pubblicato su Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVH0W16OBsTRxrhimusHhd4fZtORd-BfQmUx_75PDi2HBhqBKYV=w40-h40-c-rp-mo-ba12-br100\" alt=\"Oi! nofrio profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Oi! nofrio <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Sono appena tornato dalla clinica. Un lavoro superbo, non solo dal punto di vista estetico ma anche per la funzionalit\u00e0 masticatoria. Clinica di prim'ordine nell'accoglienza e nella professionalit\u00e0. Un caro saluto a tutta l'equipe, dalle ragazze alla reception fino ai medici chirurghi. Una menzione particolare per l'amico Albert che si \u00e8 occupato di tutta la logistica, l'accoglienza in citt\u00e0 e i vari consigli.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Nascondere\" data-open-text=\"Leggi di pi\u00f9\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1783296000\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Pubblicato su Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJ2sMKoWHCrjkKvLQFc_epyck255MT3m2QyhgBvmRuvRb5xHtw=w40-h40-c-rp-mo-br100\" alt=\"Dan Martin cocher profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Dan Martin cocher <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Un peu d'attente mais le r\u00e9sultat est excellent.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Nascondere\" data-open-text=\"Leggi di pi\u00f9\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1783123200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Pubblicato su Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocItMuZPHRfF6_WX3GyyFPtBzcepC5YrJZxOl0gosJPKNs0oYQ=w40-h40-c-rp-mo-br100\" alt=\"Luca Delli Gatti profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Luca Delli Gatti <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Smile provider clinica all'avanguardia dalla responsabile EDA a tutti i suoi collaboratori sia dal punto di vista professionale che umano molto attenti alle esigenze del paziente mi sono trovato molto bene e consiglio vivamente se avete bisogno di cure dentali di venire a Tirana un popolo cordiale ed ospitale posso solo ringraziarli per tutto di cuore \u2764\ufe0f Luca delli gatti provare per credere......<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Nascondere\" data-open-text=\"Leggi di pi\u00f9\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1783123200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Pubblicato su Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJM5b0utCl_l2fGB5u_lCHXYMI4Z6yXM7I696OqG4mFhr2YgQ=w40-h40-c-rp-mo-br100\" alt=\"luigi minonni profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> luigi minonni <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Mi sono trovato benissimo, personale gentile e disponibile. Lavoro svolto con professionalit\u00e0.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Nascondere\" data-open-text=\"Leggi di pi\u00f9\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1783123200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Pubblicato su Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJSriEzT0pfc6jGLkl5mQqR_0_iNOwM2pzAIBc1eC_0Jnmhhw=w40-h40-c-rp-mo-br100\" alt=\"anthea cuccu profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> anthea cuccu <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Edda Linda \u00e8 tutto lo staff sono eccezionali disponibili per tutti e tutto lavoro superlativo molto molto soddisfatta<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Nascondere\" data-open-text=\"Leggi di pi\u00f9\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1783036800\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Pubblicato su Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKTHGYsVkO32IPtjH3aChsELe6zaFxvRkKTr6WzeEuMEiC1tw=w40-h40-c-rp-mo-ba12-br100\" alt=\"Barbara Bertagnon profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Barbara Bertagnon <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Posso testimoniare che \u00e8 una clinica seria e professionale. Sono andata a giugno per l'impianto e torner\u00f2 a novembre per mettere quello definitivo. Sono tutti bravissimi, ma un ringraziamento speciale va a Elena, che mi ha seguito con grande disponibilit\u00e0 prima della partenza, al mio arrivo a Tirana, durante tutto il percorso e continua a seguirmi ancora oggi. Un abbraccio a tutti e a presto!!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Nascondere\" data-open-text=\"Leggi di pi\u00f9\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1783036800\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Pubblicato su Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWkUYgxI_1GF9N-F1EWeJkAgUvi7FlOyD7jHEqaqedSQeReUENn9g=w40-h40-c-rp-mo-br100\" alt=\"Maddalena Tregrosso profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Maddalena Tregrosso <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Ho finito un lavoro ai denti mi sono trovata benissimo come cure mediche dottori preparati e personale disponibile ringrazio Jonida che mi ha seguito dal primo momento molto cara competente una amica grazie<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Nascondere\" data-open-text=\"Leggi di pi\u00f9\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1782777600\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Pubblicato su Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKvDhIKr7ygOkLIN-aFj5nLhCiENoSQCR289vUzQW3ld2hfmg=w40-h40-c-rp-mo-br100\" alt=\"Ciccio Reale profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Ciccio Reale <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Prima esperienza a Tirana presso la clinica dentale Smile Provider. Un ringraziamento speciale a tutto lo staff. Personale molto professionale e soprattutto, molto educato e socievole, in clinica i pazienti vengono trattati come se fossero amici da tanti anni.\nGli autisti che giornalmente ti accompagnano in clinica anche loro sono educati.\ndevo ritornare tra sei mesi, non vedo l'ora. Si consiglia per chi volesse avere cura dei propri denti. \u2764\ufe0f<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Nascondere\" data-open-text=\"Leggi di pi\u00f9\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1782432000\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Pubblicato su Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJLgP6bSnGEWutORHV0qtDOgtnL8aNWY1B4iBryOZKl2WlkJg=w40-h40-c-rp-mo-br100\" alt=\"Roberto Grispo profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Roberto Grispo <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->\u200bIl mio percorso con Smile Provider a Tirana \u00e8 appena cominciato, ma l'impatto \u00e8 stato straordinario. Per ora ho effettuato due estrazioni con pulizia dell'osso e torner\u00f2 tra sei mesi per inserire gli impianti. Un grazie di cuore a Linda, il nostro punto di riferimento costante dall'Italia a Tirana, sempre presente e premurosa. Grazie a Eda, una vera professionista che gestisce tutto il post-preventivo e l'organizzazione in modo impeccabile. Un grazie speciale a Gioele, il medico che ha eseguito l'intervento con una delicatezza e una competenza uniche, e ad Adelina, l'anestesista, che \u00e8 stata bravissima nel farmi sentire tranquillo e non farmi sentire alcun dolore. Mi aspettano altre due trasferte, ma non potevo scegliere clinica migliore!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Nascondere\" data-open-text=\"Leggi di pi\u00f9\"><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div>   <\/div> <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-google-widget-html\" data-css-url=\"https:\/\/smile-provider.com\/wp-content\/uploads\/trustindex-google-widget.css?1780655169\"><\/div><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4b6f24 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4b6f24\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5d9dde6\" data-id=\"5d9dde6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9b69e8 elementor-widget elementor-widget-image\" data-id=\"d9b69e8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 15-04-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/FOTO__12_-removebg-preview.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d6fc833\" data-id=\"d6fc833\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32889f9 elementor-widget elementor-widget-heading\" data-id=\"32889f9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"anps-heading\" style='text-align: left;'><span class=\" anps-heading__text\" style=\"color: #FFFFFF\">Contatta Smile Provider<\/span><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc86158 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"fc86158\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"anps-heading\" style='text-align: left;'><span class=\" anps-heading__text\" style=\"color: #FFFFFF\">Puoi chiamarci al <a href=\"tel:+3901119800917\"><strong>+39 011 198 00 917<\/strong><\/a> dal luned\u00ec al venerd\u00ec dalle 9:00 alle 20:00<\/span><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34077f0 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"34077f0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-787d4cb\" data-id=\"787d4cb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-accfb19 anps-box-container__row elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"accfb19\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-953d0ed anps-box-container__column\" data-id=\"953d0ed\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3820ad1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3820ad1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-17da164\" data-id=\"17da164\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6867fc1 elementor-widget elementor-widget-heading\" data-id=\"6867fc1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"anps-heading\" style='text-align: left;'><span class=\" anps-heading__text\" style=\"color: \">Ricevi un preventivo e un piano di cure senza impegno<\/span><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6deca95 elementor-widget elementor-widget-spacer\" data-id=\"6deca95\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d932d6 elementor-widget elementor-widget-heading\" data-id=\"1d932d6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"anps-heading\" style='text-align: left;'><span class=\" anps-heading__text\" style=\"color: \">Scrivi allo staff medico<\/span><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bdc4f77 elementor-widget elementor-widget-text-editor\" data-id=\"bdc4f77\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Whatsapp: <a href=\"https:\/\/wa.me\/355698082222\">+355 698082222<\/a><br \/>Telefono italiano: <a href=\"tel:+3901119800917\">+39 011 198 00 917<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-640a052\" data-id=\"640a052\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1ce79c elementor-widget elementor-widget-shortcode\" data-id=\"e1ce79c\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f360-o2\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"360\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/3995#wpcf7-f360-o2\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"360\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f360-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"form-group col-md-12\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"fullname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome e Cognome\" value=\"\" type=\"text\" name=\"fullname\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-group col-md-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telefono\" value=\"\" type=\"tel\" name=\"your-tel\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-group col-md-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-group col-md-12\">\n\t\t<p style=\"font-size: 14px;\"><br \/>\nCarica la panoramica (se disponibile) in jpg, jpeg, png, pdf - max 5MB\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"file-200\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".jpeg,.png,.jpg,.pdf\" aria-invalid=\"false\" type=\"file\" name=\"file-200\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-group col-md-12\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Messaggio\" name=\"your-message\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-group col-md-12\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner anps-contact-button\" type=\"submit\" value=\"RICHIEDI UNA CONSULENZA PERSONALIZZATA\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-e1384da e-grid e-con-boxed e-con e-parent\" data-id=\"e1384da\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cos&#8217;\u00e8 il Turismo Dentale e perch\u00e9 scegliere l\u2019Albania? Il turismo dentale in Albania \u00e8 una soluzione sempre pi\u00f9 scelta da chi desidera cure odontoiatriche di alta qualit\u00e0 a costi ridotti. Grazie a strutture all\u2019avanguardia e professionisti altamente qualificati, \u00e8 possibile &hellip;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3995","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Turismo dentale Albania | Smile Provider Tirana<\/title>\n<meta name=\"description\" content=\"Scopri il turismo dentale in Albania con Smile Provider Tirana. Scegli i migliori specialisti, approfitta dei vantaggi del turismo dentale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smile-provider.com\/de\/zahntourismus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Turismo dentale Albania | Smile Provider Tirana\" \/>\n<meta property=\"og:description\" content=\"Scopri il turismo dentale in Albania con Smile Provider Tirana. Scegli i migliori specialisti, approfitta dei vantaggi del turismo dentale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smile-provider.com\/de\/zahntourismus\/\" \/>\n<meta property=\"og:site_name\" content=\"Smile Providers\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-27T09:31:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"21\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/smile-provider.com\/turismo-dentale\/\",\"url\":\"https:\/\/smile-provider.com\/turismo-dentale\/\",\"name\":\"Turismo dentale Albania | Smile Provider Tirana\",\"isPartOf\":{\"@id\":\"https:\/\/smile-provider.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/smile-provider.com\/turismo-dentale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/smile-provider.com\/turismo-dentale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-1.png\",\"datePublished\":\"2024-03-14T14:34:23+00:00\",\"dateModified\":\"2026-06-27T09:31:38+00:00\",\"description\":\"Scopri il turismo dentale in Albania con Smile Provider Tirana. Scegli i migliori specialisti, approfitta dei vantaggi del turismo dentale.\",\"breadcrumb\":{\"@id\":\"https:\/\/smile-provider.com\/turismo-dentale\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/smile-provider.com\/turismo-dentale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/smile-provider.com\/turismo-dentale\/#primaryimage\",\"url\":\"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-1.png\",\"contentUrl\":\"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/smile-provider.com\/turismo-dentale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/smile-provider.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Turismo Dentale Albania\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/smile-provider.com\/#website\",\"url\":\"https:\/\/smile-provider.com\/\",\"name\":\"SmileProvider\",\"description\":\"Clinica Dentale in Albania\",\"publisher\":{\"@id\":\"https:\/\/smile-provider.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/smile-provider.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/smile-provider.com\/#organization\",\"name\":\"SmileProvider - clinica dentale Albania\",\"url\":\"https:\/\/smile-provider.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/smile-provider.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/cropped-cropped-Artboard-11-1-e1670495947138.png\",\"contentUrl\":\"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/cropped-cropped-Artboard-11-1-e1670495947138.png\",\"width\":512,\"height\":512,\"caption\":\"SmileProvider - clinica dentale Albania\"},\"image\":{\"@id\":\"https:\/\/smile-provider.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zahntourismus Albanien | Smile Provider Tirana","description":"Entdecken Sie den Zahntourismus in Albanien mit Smile Provider Tirana. W\u00e4hlen Sie die besten Spezialisten und genie\u00dfen Sie die Vorteile des Zahntourismus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smile-provider.com\/de\/zahntourismus\/","og_locale":"de_DE","og_type":"article","og_title":"Turismo dentale Albania | Smile Provider Tirana","og_description":"Scopri il turismo dentale in Albania con Smile Provider Tirana. Scegli i migliori specialisti, approfitta dei vantaggi del turismo dentale.","og_url":"https:\/\/smile-provider.com\/de\/zahntourismus\/","og_site_name":"Smile Providers","article_modified_time":"2026-06-27T09:31:38+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"21\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/smile-provider.com\/turismo-dentale\/","url":"https:\/\/smile-provider.com\/turismo-dentale\/","name":"Zahntourismus Albanien | Smile Provider Tirana","isPartOf":{"@id":"https:\/\/smile-provider.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smile-provider.com\/turismo-dentale\/#primaryimage"},"image":{"@id":"https:\/\/smile-provider.com\/turismo-dentale\/#primaryimage"},"thumbnailUrl":"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-1.png","datePublished":"2024-03-14T14:34:23+00:00","dateModified":"2026-06-27T09:31:38+00:00","description":"Entdecken Sie den Zahntourismus in Albanien mit Smile Provider Tirana. W\u00e4hlen Sie die besten Spezialisten und genie\u00dfen Sie die Vorteile des Zahntourismus.","breadcrumb":{"@id":"https:\/\/smile-provider.com\/turismo-dentale\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smile-provider.com\/turismo-dentale\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smile-provider.com\/turismo-dentale\/#primaryimage","url":"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-1.png","contentUrl":"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/Senza-titolo-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/smile-provider.com\/turismo-dentale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smile-provider.com\/"},{"@type":"ListItem","position":2,"name":"Turismo Dentale Albania"}]},{"@type":"WebSite","@id":"https:\/\/smile-provider.com\/#website","url":"https:\/\/smile-provider.com\/","name":"SmileProvider","description":"Zahnklinik in Albanien","publisher":{"@id":"https:\/\/smile-provider.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smile-provider.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/smile-provider.com\/#organization","name":"SmileProvider - Zahnklinik Albanien","url":"https:\/\/smile-provider.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smile-provider.com\/#\/schema\/logo\/image\/","url":"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/cropped-cropped-Artboard-11-1-e1670495947138.png","contentUrl":"https:\/\/smile-provider.com\/wp-content\/uploads\/2024\/03\/cropped-cropped-Artboard-11-1-e1670495947138.png","width":512,"height":512,"caption":"SmileProvider - clinica dentale Albania"},"image":{"@id":"https:\/\/smile-provider.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/smile-provider.com\/de\/wp-json\/wp\/v2\/pages\/3995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smile-provider.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/smile-provider.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/smile-provider.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smile-provider.com\/de\/wp-json\/wp\/v2\/comments?post=3995"}],"version-history":[{"count":190,"href":"https:\/\/smile-provider.com\/de\/wp-json\/wp\/v2\/pages\/3995\/revisions"}],"predecessor-version":[{"id":12052,"href":"https:\/\/smile-provider.com\/de\/wp-json\/wp\/v2\/pages\/3995\/revisions\/12052"}],"wp:attachment":[{"href":"https:\/\/smile-provider.com\/de\/wp-json\/wp\/v2\/media?parent=3995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}